{"id":356,"date":"2017-03-28T19:04:02","date_gmt":"2017-03-28T17:04:02","guid":{"rendered":"http:\/\/byflorab.com\/?p=356"},"modified":"2017-10-18T10:29:40","modified_gmt":"2017-10-18T08:29:40","slug":"cookies-healthy-tout-choco-aux-flocons-davoine","status":"publish","type":"post","link":"https:\/\/byflorab.com\/index.php\/2017\/03\/28\/cookies-healthy-tout-choco-aux-flocons-davoine\/","title":{"rendered":"Cookies healthy tout choco aux flocons d&#8217;avoine"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-363\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17579890_10212417367648271_1743383987_n.jpg?resize=353%2C468&#038;ssl=1\" alt=\"\" width=\"353\" height=\"468\" data-recalc-dims=\"1\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-364\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618962_10212417367008255_357519941_n.jpg?resize=353%2C471&#038;ssl=1\" alt=\"\" width=\"353\" height=\"471\" srcset=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618962_10212417367008255_357519941_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618962_10212417367008255_357519941_n.jpg?w=540&amp;ssl=1 540w\" sizes=\"(max-width: 353px) 100vw, 353px\" data-recalc-dims=\"1\" \/><\/p>\n<p>Et voici le r\u00e9sultat d&#8217;un de mes derniers d\u00e9fis : r\u00e9ussir \u00e0 faire une recette de cookies healthy extra choco aux flocons d&#8217;avoine uniquement, avec la texture d&#8217;un vrai cookie, croustillant et tr\u00e8s l\u00e9g\u00e8rement moelleux au milieu.<\/p>\n<p>Et sinc\u00e8rement c&#8217;\u00e9tait sensationnel en bouche, ce go\u00fbt de chocolat et cette texture tr\u00e8s biscuit\u00e9e que je souhaitais, bref de la folie \ud83d\ude00 &lt;3&#8230;Je ne vous laisse imaginer l&#8217;odeur de chocolat dans tout l&#8217;appartement &lt;3. Je suis vraiment trop satisfaite de cette recette alors je vous la partage en esp\u00e9rant qu&#8217;elle vous plaise autant qu&#8217;ici, car ils sont partis vraiment tr\u00e8s tr\u00e8s vite.<\/p>\n<p><em><strong>Les ingr\u00e9dients pour 10\/12 cookies :<\/strong><\/em><\/p>\n<ul>\n<li>100g de flocons d&#8217;avoine mix\u00e9s en farine<\/li>\n<li>100g de chocolat noir 70% de cacao + 50g en morceaux + 20 pour le dessus avant d&#8217;enfourner<\/li>\n<li>2 c\u00e0s d&#8217;huile de coco<\/li>\n<li>1 oeuf<\/li>\n<li>2 c\u00e0c de levure<\/li>\n<li>1 petite pinc\u00e9e de sel<\/li>\n<li>40 g de sucre complet muscovado<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em><strong>R\u00e9alisation :\u00a0<\/strong><\/em><\/p>\n<p>Pr\u00e9chauffez votre four \u00e0 180\u00b0C. Mixez les flocons d&#8217;avoine. Ajoutez la levure et la pinc\u00e9e de sel. M\u00e9langez.<\/p>\n<p>Dans un bol, battre l&#8217;oeuf et le sucre complet puis ajoutez au m\u00e9lange sec et m\u00e9langez.<\/p>\n<p>Fa\u00eetes fondre les 100g de chocolat noir 70% de cacao avec les 2 c\u00e0s d&#8217;huile de coco. Ajoutez au m\u00e9lange pr\u00e9c\u00e9dent et m\u00e9langer.<\/p>\n<p>Ajoutez 50g de chocolat noir 70% hach\u00e9s en morceaux. M\u00e9langez. La p\u00e2te est pr\u00eate.<\/p>\n<p>Pour le fa\u00e7onnage (sur une plaque recouverte de papier sulfuris\u00e9) :<\/p>\n<p>Commencez par faire des petites boules comme sur la photo ci-dessous (j&#8217;ai roul\u00e9 des morceaux de p\u00e2te entre les paumes de mes mains pour faire ces boules, \u00e7a colle et on a les mains toutes marrons apr\u00e8s \ud83d\ude00 mais on y arrive !). Ensuite on aplatit, moi je prends le temps de bien faire les contours avec mes doigts (j&#8217;aime avoir des cookies bien nets). Enfin, posez les derniers 20g de chocolats hach\u00e9s par dessus les cookies.<\/p>\n<p>Enfournez pour 10 minutes.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-357\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17554977_10212417365928228_1863264455_n.jpg?resize=368%2C490&#038;ssl=1\" alt=\"\" width=\"368\" height=\"490\" srcset=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17554977_10212417365928228_1863264455_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17554977_10212417365928228_1863264455_n.jpg?w=540&amp;ssl=1 540w\" sizes=\"(max-width: 368px) 100vw, 368px\" data-recalc-dims=\"1\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-360\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618895_10212417366008230_861094398_n.jpg?resize=367%2C489&#038;ssl=1\" alt=\"\" width=\"367\" height=\"489\" srcset=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618895_10212417366008230_861094398_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618895_10212417366008230_861094398_n.jpg?w=540&amp;ssl=1 540w\" sizes=\"(max-width: 367px) 100vw, 367px\" data-recalc-dims=\"1\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-359\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618838_10212417366088232_1843128892_n.jpg?resize=270%2C360&#038;ssl=1\" alt=\"\" width=\"270\" height=\"360\" srcset=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618838_10212417366088232_1843128892_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17618838_10212417366088232_1843128892_n.jpg?w=540&amp;ssl=1 540w\" sizes=\"(max-width: 270px) 100vw, 270px\" data-recalc-dims=\"1\" \/><img decoding=\"async\" loading=\"lazy\" class=\"alignnone  wp-image-358\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17579941_10212417366328238_1508611679_n.jpg?resize=479%2C359&#038;ssl=1\" alt=\"\" width=\"479\" height=\"359\" srcset=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17579941_10212417366328238_1508611679_n.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17579941_10212417366328238_1508611679_n.jpg?resize=600%2C450&amp;ssl=1 600w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17579941_10212417366328238_1508611679_n.jpg?w=720&amp;ssl=1 720w\" sizes=\"(max-width: 479px) 100vw, 479px\" data-recalc-dims=\"1\" \/><\/p>\n<p>Bonne d\u00e9gustation ! \ud83d\ude00<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-362 aligncenter\" src=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17440437_10212417366568244_1662841263_n.jpg?resize=334%2C445&#038;ssl=1\" alt=\"\" width=\"334\" height=\"445\" srcset=\"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17440437_10212417366568244_1662841263_n.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17440437_10212417366568244_1662841263_n.jpg?w=540&amp;ssl=1 540w\" sizes=\"(max-width: 334px) 100vw, 334px\" data-recalc-dims=\"1\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et voici le r\u00e9sultat d&#8217;un de mes derniers d\u00e9fis : r\u00e9ussir \u00e0 faire une recette de cookies healthy extra choco aux flocons d&#8217;avoine uniquement, avec la texture d&#8217;un vrai cookie, croustillant et tr\u00e8s l\u00e9g\u00e8rement moelleux au milieu. Et sinc\u00e8rement c&#8217;\u00e9tait sensationnel en bouche, ce go\u00fbt&nbsp;<a class=\"read-more\" href=\"https:\/\/byflorab.com\/index.php\/2017\/03\/28\/cookies-healthy-tout-choco-aux-flocons-davoine\/\">&hellip;<\/a><\/p>\n","protected":false},"author":1,"featured_media":365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"categories":[14],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/byflorab.com\/wp-content\/uploads\/2017\/03\/17619197_10212417365848226_2047373683_n.jpg?fit=576%2C720&ssl=1","_links":{"self":[{"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/posts\/356"}],"collection":[{"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":2,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"predecessor-version":[{"id":367,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/posts\/356\/revisions\/367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/media\/365"}],"wp:attachment":[{"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/byflorab.com\/index.php\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}